{"id":4176,"date":"2026-06-30T11:12:11","date_gmt":"2026-06-30T11:12:11","guid":{"rendered":"https:\/\/eu.goshenisafaris.com\/zahlungs-und-stornierungsbedingungen\/"},"modified":"2026-06-30T11:12:11","modified_gmt":"2026-06-30T11:12:11","slug":"zahlungs-und-stornierungsbedingungen","status":"publish","type":"page","link":"https:\/\/eu.goshenisafaris.com\/de\/zahlungs-und-stornierungsbedingungen\/","title":{"rendered":"Zahlungs- und Stornierungsbedingungen"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4176","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/eu.goshenisafaris.com\/de\/wp-json\/wp\/v2\/pages\/4176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eu.goshenisafaris.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/eu.goshenisafaris.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/eu.goshenisafaris.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eu.goshenisafaris.com\/de\/wp-json\/wp\/v2\/comments?post=4176"}],"version-history":[{"count":0,"href":"https:\/\/eu.goshenisafaris.com\/de\/wp-json\/wp\/v2\/pages\/4176\/revisions"}],"wp:attachment":[{"href":"https:\/\/eu.goshenisafaris.com\/de\/wp-json\/wp\/v2\/media?parent=4176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}